{"id":70509,"date":"2025-11-05T14:55:34","date_gmt":"2025-11-05T14:55:34","guid":{"rendered":"https:\/\/gayfappy.com\/?p=70509"},"modified":"2025-11-05T14:55:34","modified_gmt":"2025-11-05T14:55:34","slug":"juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp","status":"publish","type":"post","link":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/","title":{"rendered":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp"},"content":{"rendered":"<p class='post_desc'>Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp<\/p>\n<p> <!--more--> <\/p>\n<div class='thumbs_wrap'><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' class='a_thumb_img'><br \/>\n                  <\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p class='post_desc'>Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp<\/p>\n<p> <!--more--> <\/p>\n<div class='thumbs_wrap'><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/368d0557af8af60f4d3abf3ece87dec7.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/d22c1db4bad51c03b99bde76a3cb5dab.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/265a4ff33c4f6b10ec773ed626c49351.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/7cbeff7167f0128c0e6fc057e50620ee.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/9c16d988d0c5103253bb55e4d2d59571.png' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/a26758bdee1f64744a5bfb6c920f5c8a.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/4a7c42ee6bb4bca46e10e6baa1697c58.jpg' class='a_thumb_img'><br \/>\n                  <\/a><a href='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' data-fancybox='gallery' data-src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' class='a_thumb'><br \/>\n                    <img src='https:\/\/gayfappy.com\/rss\/thumbs\/ziggy_csr\/79b7532ea2c2c1a37724764d619c446d\/709dda85eb2690027eb291e8e740d57d.jpg' class='a_thumb_img'><br \/>\n                  <\/a><\/div>\n","protected":false},"author":192,"featured_media":70510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"Default","format":"standard","meta":{"footnotes":""},"categories":[2,3,4,5,6,7],"tags":[],"class_list":["post-70509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adult","category-amateur","category-cute","category-gay","category-guys","category-men","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>juan pablo 21 a\u00f1os la serena pasivo tengo su wsp<\/title>\n<meta name=\"description\" content=\"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp\" \/>\n<meta property=\"og:description\" content=\"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/\" \/>\n<meta property=\"og:site_name\" content=\"Gay Fappy\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T14:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"422\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veteranrider\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"veteranrider\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/\"},\"author\":{\"name\":\"veteranrider\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/#\\\/schema\\\/person\\\/eccf579713c9282080eff7973392ac73\"},\"headline\":\"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp\",\"datePublished\":\"2025-11-05T14:55:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/\"},\"wordCount\":20,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gayfappy.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg\",\"articleSection\":[\"Adult\",\"Amateur\",\"Cute\",\"Gay\",\"Guys\",\"Men\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/\",\"url\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/\",\"name\":\"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gayfappy.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg\",\"datePublished\":\"2025-11-05T14:55:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/#\\\/schema\\\/person\\\/eccf579713c9282080eff7973392ac73\"},\"description\":\"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gayfappy.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg\",\"contentUrl\":\"https:\\\/\\\/gayfappy.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg\",\"width\":422,\"height\":750,\"caption\":\"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/70509\\\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gayfappy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/#website\",\"url\":\"https:\\\/\\\/gayfappy.com\\\/\",\"name\":\"Gay Fappy\",\"description\":\"Photos, videos and gifs of beautiful and sex guys from around the world.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gayfappy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gayfappy.com\\\/#\\\/schema\\\/person\\\/eccf579713c9282080eff7973392ac73\",\"name\":\"veteranrider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g\",\"caption\":\"veteranrider\"},\"url\":\"https:\\\/\\\/gayfappy.com\\\/index.php\\\/author\\\/veteranrider\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp","description":"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/","og_locale":"en_US","og_type":"article","og_title":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp","og_description":"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp","og_url":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/","og_site_name":"Gay Fappy","article_published_time":"2025-11-05T14:55:34+00:00","og_image":[{"width":422,"height":750,"url":"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg","type":"image\/jpeg"}],"author":"veteranrider","twitter_card":"summary_large_image","twitter_misc":{"Written by":"veteranrider"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#article","isPartOf":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/"},"author":{"name":"veteranrider","@id":"https:\/\/gayfappy.com\/#\/schema\/person\/eccf579713c9282080eff7973392ac73"},"headline":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp","datePublished":"2025-11-05T14:55:34+00:00","mainEntityOfPage":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/"},"wordCount":20,"commentCount":0,"image":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#primaryimage"},"thumbnailUrl":"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg","articleSection":["Adult","Amateur","Cute","Gay","Guys","Men"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/","url":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/","name":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp","isPartOf":{"@id":"https:\/\/gayfappy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#primaryimage"},"image":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#primaryimage"},"thumbnailUrl":"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg","datePublished":"2025-11-05T14:55:34+00:00","author":{"@id":"https:\/\/gayfappy.com\/#\/schema\/person\/eccf579713c9282080eff7973392ac73"},"description":"Juan Pablo, 21 a\u00f1os, la serena pasivo tengo su wsp","breadcrumb":{"@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#primaryimage","url":"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg","contentUrl":"https:\/\/gayfappy.com\/wp-content\/uploads\/2025\/11\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp.jpg","width":422,"height":750,"caption":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp"},{"@type":"BreadcrumbList","@id":"https:\/\/gayfappy.com\/index.php\/70509\/juan-pablo-21-anos-la-serena-pasivo-tengo-su-wsp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gayfappy.com\/"},{"@type":"ListItem","position":2,"name":"juan pablo 21 a\u00f1os la serena pasivo tengo su wsp"}]},{"@type":"WebSite","@id":"https:\/\/gayfappy.com\/#website","url":"https:\/\/gayfappy.com\/","name":"Gay Fappy","description":"Photos, videos and gifs of beautiful and sex guys from around the world.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gayfappy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/gayfappy.com\/#\/schema\/person\/eccf579713c9282080eff7973392ac73","name":"veteranrider","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7842bf99da02e946261639fc4013dfad7e3a4f6c82e136dbf3a70489c32e898?s=96&d=mm&r=g","caption":"veteranrider"},"url":"https:\/\/gayfappy.com\/index.php\/author\/veteranrider\/"}]}},"_links":{"self":[{"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/posts\/70509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/comments?post=70509"}],"version-history":[{"count":1,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/posts\/70509\/revisions"}],"predecessor-version":[{"id":70661,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/posts\/70509\/revisions\/70661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/media\/70510"}],"wp:attachment":[{"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/media?parent=70509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/categories?post=70509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gayfappy.com\/index.php\/wp-json\/wp\/v2\/tags?post=70509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}